{"id":21512,"date":"2021-07-07T09:36:57","date_gmt":"2021-07-07T07:36:57","guid":{"rendered":"https:\/\/sim-tailleur-pierre-notre-dame-paris-monuments-historiques.fr\/?page_id=21512"},"modified":"2025-04-23T15:50:36","modified_gmt":"2025-04-23T13:50:36","slug":"notre-dame","status":"publish","type":"page","link":"https:\/\/sim-tailleur-pierre-notre-dame-paris-monuments-historiques.fr\/index.php\/notre-dame\/","title":{"rendered":"Notre Dame"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column width=\u00a0\u00bb1\/4&Prime;][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime;]<div class=\"dfd-spacer-module\"  data-units=\"px\" data-wide_resolution=\"1280\" data-wide_size=\"150\" data-normal_resolution=\"1024\" data-normal_size=\"150\" data-tablet_resolution=\"800\" data-tablet_size=\"50\" data-mobile_resolution=\"480\" data-mobile_size=\"20\" style=\"height: 150px;\"><\/div><div class=\"dfd-heading-shortcode\"><div class=\"dfd-heading-module-wrap  text-center style_01 dfd-heading-6a57d7ea6dba5 dfd-disable-resposive-headings\" id=\"dfd-heading-6a57d7ea6dba5\" ><div class=\"inline-block\"><div class=\"dfd-heading-module\"><h5 class=\"widget-title dfd-title \" style=\"\"><\/p>\n<h3>NOTRE DAME DE PARIS<span class=\"dfd-big-number-responcive\" style=\"color: #f9593e; font-size: 150px;\">.<\/span><span class=\"dfd-big-number-responcive\" style=\"color: #e5e5e5; font-size: 150px;\">05<\/span><\/h3>\n<p><\/h5><div class=\"dfd-heading-delimiter dfd-img-lazy-load\"><\/div><\/div><\/div><\/div><script type=\"text\/javascript\">\r\n\t\t\t\t\t\t\t\t\t(function($) {\r\n\t\t\t\t\t\t\t\t\t\t$(\"head\").append(\"<style>.dfd-heading-6a57d7ea6dba5.dfd-heading-module-wrap .dfd-heading-module .dfd-heading-delimiter {border-bottom-style:solid;border-bottom-width:1px;width:100px;border-bottom-color:#dddddd;}.dfd-heading-6a57d7ea6dba5.dfd-heading-module-wrap .dfd-heading-module .dfd-heading-delimiter {margin-top:10px;margin-bottom:10px;}<\/style>\");\r\n\t\t\t\t\t\t\t\t\t})(jQuery);\r\n\t\t\t\t\t\t\t\t<\/script><\/div>[\/vc_column][vc_column width=\u00a0\u00bb1\/4&Prime;][\/vc_column][\/vc_row][vc_row][vc_column width=\u00a0\u00bb1\/4&Prime;][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime;]<div class=\"dfd-spacer-module\"  data-units=\"px\" data-wide_resolution=\"1280\" data-wide_size=\"50\" data-normal_resolution=\"1024\" data-normal_size=\"50\" data-tablet_resolution=\"800\" data-tablet_size=\"30\" data-mobile_resolution=\"480\" data-mobile_size=\"20\" style=\"height: 50px;\"><\/div>[vc_column_text css_animation=\u00a0\u00bbbounceInUp\u00a0\u00bb css=\u00a0\u00bb\u00a0\u00bb]<strong>Les Grandes \u00c9tapes de la R\u00e9novation<\/strong><\/p>\n<p>&nbsp;<\/p>\n<ol>\n<li><strong> S\u00e9curisation et Nettoyage (2019-2021)<\/strong><\/li>\n<\/ol>\n<p>&#8211; S\u00e9curisation : Apr\u00e8s l&rsquo;incendie du 15 avril 2019, la premi\u00e8re \u00e9tape a \u00e9t\u00e9 de s\u00e9curiser la structure de la cath\u00e9drale. Cela comprenait le d\u00e9montage des \u00e9chafaudages endommag\u00e9s et la consolidation des parties fragilis\u00e9es de l&rsquo;\u00e9difice<\/p>\n<p>&nbsp;<\/p>\n<p>&#8211; Nettoyage : Une campagne de nettoyage de l&rsquo;int\u00e9rieur de la cath\u00e9drale a \u00e9t\u00e9 lanc\u00e9e pour enlever les d\u00e9bris et les r\u00e9sidus de l&rsquo;incendie<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<ol start=\"2\">\n<li><strong> Reconstruction et Restauration (2021-2024)<\/strong><\/li>\n<\/ol>\n<p>&#8211; Reconstruction de la Charpente et de la Fl\u00e8che : La charpente en bois et la fl\u00e8che ont \u00e9t\u00e9 reconstruites \u00e0 l&rsquo;identique. Des ch\u00eanes centenaires ont \u00e9t\u00e9 utilis\u00e9s pour la charpente, et la fl\u00e8che a \u00e9t\u00e9 reconstruite selon les plans originaux<\/p>\n<p>&nbsp;<\/p>\n<p>&#8211; Restauration des Vo\u00fbtes et des Murs : Les vo\u00fbtes et les murs ont \u00e9t\u00e9 consolid\u00e9s et restaur\u00e9s. Les tailleurs de pierre ont jou\u00e9 un r\u00f4le crucial dans cette phase, en rempla\u00e7ant les pierres endommag\u00e9es et en consolidant la structure<\/p>\n<p>&nbsp;<\/p>\n<p>&#8211; R\u00e9novation des Vitraux et des Sculptures : Les vitraux et les sculptures ont \u00e9t\u00e9 nettoy\u00e9s et restaur\u00e9s. Les vitraillistes ont travaill\u00e9 \u00e0 la restauration des vitraux, tandis que les sculpteurs ont restaur\u00e9 les statues et les ornements<\/p>\n<ol start=\"3\">\n<li><strong>Phase Finale et R\u00e9ouverture (2024)<\/strong><\/li>\n<\/ol>\n<p>&#8211; Fin des Travaux : Les travaux de r\u00e9novation se sont achev\u00e9s en d\u00e9cembre 2024, permettant la r\u00e9ouverture de la cath\u00e9drale au public. Cependant, des travaux de restauration suppl\u00e9mentaires sont pr\u00e9vus pour consolider certains \u00e9l\u00e9ments fragilis\u00e9s, comme les arcs-boutants du ch\u0153ur<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Conclusion<\/strong><\/p>\n<p>La r\u00e9novation de Notre-Dame de Paris a \u00e9t\u00e9 un chantier titanesque qui a mobilis\u00e9 des centaines d&rsquo;artisans et de professionnels du patrimoine. Gr\u00e2ce \u00e0 leur savoir-faire et \u00e0 leur d\u00e9vouement, la cath\u00e9drale a pu retrouver sa splendeur d&rsquo;antan et rouvrir ses portes au public en d\u00e9cembre 2024. Ce projet a \u00e9galement permis de mettre en lumi\u00e8re l&rsquo;importance de pr\u00e9server et de transmettre les m\u00e9tiers d&rsquo;art, essentiels \u00e0 la conservation de notre patrimoine[\/vc_column_text][\/vc_column][vc_column width=\u00a0\u00bb1\/4&Prime;][\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"dfd-spacer-module\"  data-units=\"px\" data-wide_resolution=\"1280\" data-wide_size=\"100\" data-normal_resolution=\"1024\" data-normal_size=\"70\" data-tablet_resolution=\"800\" data-tablet_size=\"50\" data-mobile_resolution=\"480\" data-mobile_size=\"30\" style=\"height: 100px;\"><\/div>[\/vc_column][\/vc_row][vc_row dfd_row_config=\u00a0\u00bbfull_width_content\u00a0\u00bb][vc_column width=\u00a0\u00bb1\/6&Prime;][vc_single_image image=\u00a0\u00bb22282&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb css=\u00a0\u00bb\u00a0\u00bb][\/vc_column][vc_column width=\u00a0\u00bb1\/6&Prime;][vc_single_image image=\u00a0\u00bb22283&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb css=\u00a0\u00bb\u00a0\u00bb][\/vc_column][vc_column width=\u00a0\u00bb1\/6&Prime;][vc_single_image image=\u00a0\u00bb22285&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb css=\u00a0\u00bb\u00a0\u00bb][\/vc_column][vc_column width=\u00a0\u00bb1\/6&Prime;][vc_single_image image=\u00a0\u00bb22284&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb css=\u00a0\u00bb\u00a0\u00bb][\/vc_column][vc_column width=\u00a0\u00bb1\/6&Prime;][vc_single_image image=\u00a0\u00bb22303&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb css=\u00a0\u00bb\u00a0\u00bb][\/vc_column][vc_column width=\u00a0\u00bb1\/6&Prime;][vc_single_image image=\u00a0\u00bb22287&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb css=\u00a0\u00bb\u00a0\u00bb][\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"dfd-spacer-module\"  data-units=\"px\" data-wide_resolution=\"1280\" data-wide_size=\"50\" data-normal_resolution=\"1024\" data-normal_size=\"40\" data-tablet_resolution=\"800\" data-tablet_size=\"30\" data-mobile_resolution=\"480\" data-mobile_size=\"20\" style=\"height: 50px;\"><\/div>[\/vc_column][\/vc_row][vc_row dfd_row_config=\u00a0\u00bbfull_width_content\u00a0\u00bb][vc_column width=\u00a0\u00bb1\/6&Prime;][vc_single_image image=\u00a0\u00bb22288&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb css=\u00a0\u00bb\u00a0\u00bb][\/vc_column][vc_column width=\u00a0\u00bb1\/6&Prime;][vc_single_image image=\u00a0\u00bb22292&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb css=\u00a0\u00bb\u00a0\u00bb][\/vc_column][vc_column width=\u00a0\u00bb1\/6&Prime;][vc_single_image image=\u00a0\u00bb22291&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb css=\u00a0\u00bb\u00a0\u00bb][\/vc_column][vc_column width=\u00a0\u00bb1\/6&Prime;][vc_single_image image=\u00a0\u00bb22293&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb css=\u00a0\u00bb\u00a0\u00bb][\/vc_column][vc_column width=\u00a0\u00bb1\/6&Prime;][vc_single_image image=\u00a0\u00bb22286&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb css=\u00a0\u00bb\u00a0\u00bb][\/vc_column][vc_column width=\u00a0\u00bb1\/6&Prime;][vc_single_image image=\u00a0\u00bb22289&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb css=\u00a0\u00bb\u00a0\u00bb][\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"dfd-spacer-module\"  data-units=\"px\" data-wide_resolution=\"1280\" data-wide_size=\"50\" data-normal_resolution=\"1024\" data-normal_size=\"40\" data-tablet_resolution=\"800\" data-tablet_size=\"30\" data-mobile_resolution=\"480\" data-mobile_size=\"20\" style=\"height: 50px;\"><\/div>[\/vc_column][\/vc_row][vc_row dfd_row_config=\u00a0\u00bbfull_width_content\u00a0\u00bb][vc_column width=\u00a0\u00bb1\/6&Prime;][vc_single_image image=\u00a0\u00bb22290&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb css=\u00a0\u00bb\u00a0\u00bb][\/vc_column][vc_column width=\u00a0\u00bb1\/6&Prime;][vc_single_image image=\u00a0\u00bb22302&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb css=\u00a0\u00bb\u00a0\u00bb][\/vc_column][vc_column width=\u00a0\u00bb1\/6&Prime;][vc_single_image image=\u00a0\u00bb22300&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb css=\u00a0\u00bb\u00a0\u00bb][\/vc_column][vc_column width=\u00a0\u00bb1\/6&Prime;][vc_single_image image=\u00a0\u00bb22299&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb css=\u00a0\u00bb\u00a0\u00bb][\/vc_column][vc_column width=\u00a0\u00bb1\/6&Prime;][vc_single_image image=\u00a0\u00bb22301&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb css=\u00a0\u00bb\u00a0\u00bb][\/vc_column][vc_column width=\u00a0\u00bb1\/6&Prime;][vc_single_image image=\u00a0\u00bb22298&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb css=\u00a0\u00bb\u00a0\u00bb][\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"dfd-spacer-module\"  data-units=\"px\" data-wide_resolution=\"1280\" data-wide_size=\"50\" data-normal_resolution=\"1024\" data-normal_size=\"40\" data-tablet_resolution=\"800\" data-tablet_size=\"30\" data-mobile_resolution=\"480\" data-mobile_size=\"20\" style=\"height: 50px;\"><\/div>[\/vc_column][\/vc_row][vc_row dfd_row_config=\u00a0\u00bbfull_width_content\u00a0\u00bb][vc_column width=\u00a0\u00bb1\/6&Prime;][\/vc_column][vc_column width=\u00a0\u00bb1\/6&Prime;][vc_single_image image=\u00a0\u00bb22297&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb css=\u00a0\u00bb\u00a0\u00bb][\/vc_column][vc_column width=\u00a0\u00bb1\/6&Prime;][vc_single_image image=\u00a0\u00bb22296&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb css=\u00a0\u00bb\u00a0\u00bb][\/vc_column][vc_column width=\u00a0\u00bb1\/6&Prime;][vc_single_image image=\u00a0\u00bb22295&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb css=\u00a0\u00bb\u00a0\u00bb][\/vc_column][vc_column width=\u00a0\u00bb1\/6&Prime;][vc_single_image image=\u00a0\u00bb22294&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb css=\u00a0\u00bb\u00a0\u00bb][\/vc_column][vc_column width=\u00a0\u00bb1\/6&Prime;][\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"dfd-spacer-module\"  data-units=\"px\" data-wide_resolution=\"1280\" data-wide_size=\"50\" data-normal_resolution=\"1024\" data-normal_size=\"40\" data-tablet_resolution=\"800\" data-tablet_size=\"30\" data-mobile_resolution=\"480\" data-mobile_size=\"20\" style=\"height: 50px;\"><\/div>[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column width=\u00a0\u00bb1\/4&Prime;][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime;][\/vc_column][vc_column width=\u00a0\u00bb1\/4&Prime;][\/vc_column][\/vc_row][vc_row][vc_column width=\u00a0\u00bb1\/4&Prime;][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_column_text css_animation=\u00a0\u00bbbounceInUp\u00a0\u00bb css=\u00a0\u00bb\u00a0\u00bb]Les Grandes \u00c9tapes de la R\u00e9novation &nbsp; S\u00e9curisation et Nettoyage (2019-2021) &#8211; S\u00e9curisation : Apr\u00e8s l&rsquo;incendie du 15 avril 2019, la premi\u00e8re \u00e9tape<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-custom.php","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-21512","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Notre Dame - SIM PARIS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sim-tailleur-pierre-notre-dame-paris-monuments-historiques.fr\/index.php\/notre-dame\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Notre Dame - SIM PARIS\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column width=\u00a0\u00bb1\/4&Prime;][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime;][\/vc_column][vc_column width=\u00a0\u00bb1\/4&Prime;][\/vc_column][\/vc_row][vc_row][vc_column width=\u00a0\u00bb1\/4&Prime;][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_column_text css_animation=\u00a0\u00bbbounceInUp\u00a0\u00bb css=\u00a0\u00bb\u00a0\u00bb]Les Grandes \u00c9tapes de la R\u00e9novation &nbsp; S\u00e9curisation et Nettoyage (2019-2021) &#8211; S\u00e9curisation : Apr\u00e8s l&rsquo;incendie du 15 avril 2019, la premi\u00e8re \u00e9tape\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sim-tailleur-pierre-notre-dame-paris-monuments-historiques.fr\/index.php\/notre-dame\/\" \/>\n<meta property=\"og:site_name\" content=\"SIM PARIS\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-23T13:50:36+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Notre Dame - SIM PARIS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sim-tailleur-pierre-notre-dame-paris-monuments-historiques.fr\/index.php\/notre-dame\/","og_locale":"fr_FR","og_type":"article","og_title":"Notre Dame - SIM PARIS","og_description":"[vc_row][vc_column width=\u00a0\u00bb1\/4&Prime;][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime;][\/vc_column][vc_column width=\u00a0\u00bb1\/4&Prime;][\/vc_column][\/vc_row][vc_row][vc_column width=\u00a0\u00bb1\/4&Prime;][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_column_text css_animation=\u00a0\u00bbbounceInUp\u00a0\u00bb css=\u00a0\u00bb\u00a0\u00bb]Les Grandes \u00c9tapes de la R\u00e9novation &nbsp; S\u00e9curisation et Nettoyage (2019-2021) &#8211; S\u00e9curisation : Apr\u00e8s l&rsquo;incendie du 15 avril 2019, la premi\u00e8re \u00e9tape","og_url":"https:\/\/sim-tailleur-pierre-notre-dame-paris-monuments-historiques.fr\/index.php\/notre-dame\/","og_site_name":"SIM PARIS","article_modified_time":"2025-04-23T13:50:36+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sim-tailleur-pierre-notre-dame-paris-monuments-historiques.fr\/index.php\/notre-dame\/","url":"https:\/\/sim-tailleur-pierre-notre-dame-paris-monuments-historiques.fr\/index.php\/notre-dame\/","name":"Notre Dame - SIM PARIS","isPartOf":{"@id":"https:\/\/sim-tailleur-pierre-notre-dame-paris-monuments-historiques.fr\/#website"},"datePublished":"2021-07-07T07:36:57+00:00","dateModified":"2025-04-23T13:50:36+00:00","breadcrumb":{"@id":"https:\/\/sim-tailleur-pierre-notre-dame-paris-monuments-historiques.fr\/index.php\/notre-dame\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sim-tailleur-pierre-notre-dame-paris-monuments-historiques.fr\/index.php\/notre-dame\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sim-tailleur-pierre-notre-dame-paris-monuments-historiques.fr\/index.php\/notre-dame\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/sim-tailleur-pierre-notre-dame-paris-monuments-historiques.fr\/"},{"@type":"ListItem","position":2,"name":"Notre Dame"}]},{"@type":"WebSite","@id":"https:\/\/sim-tailleur-pierre-notre-dame-paris-monuments-historiques.fr\/#website","url":"https:\/\/sim-tailleur-pierre-notre-dame-paris-monuments-historiques.fr\/","name":"SIM PARIS","description":"Recrutement placement Paris 12","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sim-tailleur-pierre-notre-dame-paris-monuments-historiques.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/sim-tailleur-pierre-notre-dame-paris-monuments-historiques.fr\/index.php\/wp-json\/wp\/v2\/pages\/21512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sim-tailleur-pierre-notre-dame-paris-monuments-historiques.fr\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sim-tailleur-pierre-notre-dame-paris-monuments-historiques.fr\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sim-tailleur-pierre-notre-dame-paris-monuments-historiques.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sim-tailleur-pierre-notre-dame-paris-monuments-historiques.fr\/index.php\/wp-json\/wp\/v2\/comments?post=21512"}],"version-history":[{"count":24,"href":"https:\/\/sim-tailleur-pierre-notre-dame-paris-monuments-historiques.fr\/index.php\/wp-json\/wp\/v2\/pages\/21512\/revisions"}],"predecessor-version":[{"id":22374,"href":"https:\/\/sim-tailleur-pierre-notre-dame-paris-monuments-historiques.fr\/index.php\/wp-json\/wp\/v2\/pages\/21512\/revisions\/22374"}],"wp:attachment":[{"href":"https:\/\/sim-tailleur-pierre-notre-dame-paris-monuments-historiques.fr\/index.php\/wp-json\/wp\/v2\/media?parent=21512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}